{"id":12078,"date":"2021-02-17T00:00:00","date_gmt":"2021-02-17T00:00:00","guid":{"rendered":"https:\/\/phakhaolao.la\/story\/%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%80%e0%ba%ab%e0%ba%b1%e0%ba%94%e0%ba%82%e0%ba%ad%e0%ba%99%e0%ba%82%e0%ba%b2%e0%ba%a7\/"},"modified":"2024-11-25T12:51:03","modified_gmt":"2024-11-25T12:51:03","slug":"%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%80%e0%ba%ab%e0%ba%b1%e0%ba%94%e0%ba%82%e0%ba%ad%e0%ba%99%e0%ba%82%e0%ba%b2%e0%ba%a7","status":"publish","type":"story","link":"https:\/\/phakhaolao.la\/en\/story\/%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%80%e0%ba%ab%e0%ba%b1%e0%ba%94%e0%ba%82%e0%ba%ad%e0%ba%99%e0%ba%82%e0%ba%b2%e0%ba%a7\/","title":{"rendered":"\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec0\u0eab\u0eb1\u0e94\u0e82\u0ead\u0e99\u0e82\u0eb2\u0ea7"},"content":{"rendered":"<p>\u0ec0\u0eab\u0eb1\u0e94\u0e82\u0ead\u0e99\u0e82\u0eb2\u0ea7\u0ec0\u0e9b\u0eb1\u0e99\u0ec0\u0eab\u0eb1\u0e94\u0e97\u0eb5\u0ea1\u0eb1\u0e81\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0eae\u0ec9\u0ead\u0e99 \u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0ea1\u0ec8\u0e99\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e95\u0ebb\u0ec9\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0e95\u0ec8 \u0ec0\u0e94\u0eb7\u0ead\u0e99 \u0e81\u0eb8\u0ea1\u0e9e\u0eb2 \u0ec0\u0e96\u0eb4\u0e87\u0ec0\u0e94\u0eb7\u0ead\u0e99 \u0ea1\u0eb4\u0e96\u0eb8\u0e99\u0eb2. \u0ec0\u0eab\u0eb1\u0e94\u0e82\u0ead\u0e99\u0e82\u0eb2\u0ea7\u0ec0\u0e9b\u0eb1\u0e99\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0ec0\u0eab\u0eb1\u0e94\u0e94\u0ead\u0e81\u0e99\u0ec9\u0ead\u0e8d \u0ec1\u0e95\u0ec8\u0ea1\u0eb5\u0ea5\u0ebb\u0e94\u0e8a\u0eb2\u0e94\u0ec1\u0e8a\u0e9a, \u0ea1\u0eb5\u0e97\u0eb2\u0e94\u0ea7\u0eb4\u0e95\u0eb2\u0ea1\u0eb4\u0e99\u0eaa\u0eb9\u0e87 \u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e9b\u0eb8\u0e87\u0ec1\u0e95\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0ead\u0eb2\u0eab\u0eb2\u0e99\u0ec4\u0e94\u0ec9\u0eab\u0ea5\u0eb2\u0e8d\u0ec0\u0ea1\u0e99\u0eb9,\u0e96\u0ec9\u0eb2\u0e9b\u0eb9\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ecd\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0eb2\u0e8d\u0eaa\u0eb2\u0ec9\u0e87\u0ea5\u0eb2\u0e8d\u0eae\u0eb1\u0e9a\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0e84\u0ead\u0e9a\u0e84\u0ebb\u0ea7\u0ead\u0eb5\u0e81\u0e94\u0ec9\u0ea7\u0e8d.<\/p>\n<p class=\"question\">1. \u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ead\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81<\/p>\n<ol>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0e81\u0ebd\u0ea1\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0e97\u0eb5\u0ec8:\u00a0\u0e9a\u0ec8\u0ead\u0e99\u0e95\u0eb1\u0ec9\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94\u0e84\u0ea7\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0e9a\u0ec8\u0ead\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e96\u0ec8\u0eb2\u0e8d\u0ec0\u0e97\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0ec0\u0e9b\u0eb1\u0e99\u0ec2\u0e99\u0e99, \u0ead\u0eb0\u0e99\u0eb2\u0ec4\u0ea1\u0e87\u0ec8\u0eb2\u0e8d,\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e82\u0ead\u0e87\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0e9b\u0eb9\u0e81 4 X 6 \u0ec1\u0ea1\u0eb1\u0e94,\u0ea1\u0eb8\u0e87 \u0ec1\u0ea5\u0eb0 \u0ec1\u0ead\u0ec9\u0ea1\u0e94\u0ea7\u0ec9\u0e8d\u0ec1\u0e9e\u0ea2\u0eb2\u0e87.<\/li>\n<li>\u0e81\u0eb2\u0e99\u0e81\u0ebd\u0ea1\u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99: \u0e96\u0eb1\u0e87\u0edc\u0eb6\u0ec9\u0ec9\u0ec9\u0e87, \u0e96\u0ebb\u0e87\u0ea2\u0eb2\u0e87\u0e9b\u0eb9\u0e81\u0ec0\u0eab\u0eb1\u0e94, \u0ea2\u0eb2\u0e87\u0e9a\u0ea7\u0ec9\u0e87, \u0e9b\u0ead\u0e81\u0e84\u0ecd\u0e96\u0ebb\u0e87, \u0eaa\u0ecd\u0eb2\u0ea5\u0eb5, \u0e95\u0eb0\u0e81\u0ebd\u0e87\u0ec0\u0eab\u0ebc\u0ebb\u0ec9\u0eb2 90, \u0ec0\u0eab\u0ebc\u0ebb\u0ec9\u0eb2 90, \u0e8a\u0eb4\u0e87\u0e8a\u0eb1\u0ec8\u0e87\u0e99\u0ecd\u0ec9\u0eb2\u0edc\u0eb1\u0e81, \u0ec0\u0e88\u0ec9\u0e8d (\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e9b\u0eb4\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0e81\u0ec9\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94), \u0e94\u0eb5\u0ec0\u0e81\u0eb7\u0ead, \u0ea2\u0eb4\u0e9a\u0e8a\u0ecd\u0eb2, \u0e9b\u0eb9\u0e99\u0e82\u0eb2\u0ea7, \u0eae\u0ecd\u0eb2\u0ead\u0ec8\u0ead\u0e99, \u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e9b\u0ebd\u0e99, \u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec0\u0eab\u0eb1\u0e94.<\/li>\n<li>\u0ea7\u0eb4\u0e97\u0eb5\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e82\u0eb5\u0ec9\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e8d\u0ec3\u0eaa\u0ec8\u0eaa\u0ec8\u0ea7\u0e99\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1: \u0e82\u0eb5\u0ec9\u0ec0\u0ea5\u0eb7\u0ead\u0e8d 100 \u0e81\u0eb4\u0ec2\u0ea5\u0e81\u0ebc\u0eb2\u0ea1, \u0e94\u0eb5\u0ec0\u0e81\u0eb7\u0ead 3 \u0e82\u0eb5\u0e94, \u0ea2\u0eb4\u0e9a\u0e8a\u0ecd\u0ec9\u0eb2\u00a01\u00a0\u0e81\u0eb4\u0ec2\u0ea5\u0e81\u0ebc\u0eb2\u0ea1, \u0e9b\u0eb9\u0e99\u0e82\u0eb2\u0ea7 1 \u0e81\u0eb4\u0ec2\u0ea5\u0e81\u0ebc\u0eb2\u0ea1,\u00a0\u0eae\u0ecd\u0eb2\u0ead\u0ec8\u0ead\u0e99 1\u00a0\u0e81\u0eb4\u0ec2\u0ea5\u0e81\u0ebc\u0eb2\u0ea1,\u00a0\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e9b\u0ebd\u0e99 3\u00a0\u0e81\u0eb4\u0ec2\u0ea5\u0e81\u0ebc\u0eb2\u0ea1, \u0ec0\u0ead\u0ebb\u0eb2\u0e82\u0eb5\u0ec9\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e8d \u0ec1\u0ea5\u0eb0 \u0eaa\u0ec8\u0ea7\u0e99\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0ea1\u0eb2\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e81\u0eb1\u0e99 \u0e84\u0ebb\u0e99\u0ec3\u0eab\u0ec9\u0ea5\u0eb0\u0ead\u0ebd\u0e94, \u0eab\u0ebb\u0e94\u0e99\u0ecd\u0ec9\u0eb2\u0ec3\u0eab\u0ec9\u0e84\u0ea7\u0eb2\u0ea1\u0e8a\u0ec8\u0eb9\u0ea1\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 65 &#8211; 70% \u0ec1\u0ea5\u0ec9\u0ea7\u0e99\u0ecd\u0eb2\u0ec4\u0e9b\u0e9a\u0eb1\u0e99\u0e88\u0eb8\u0ec3\u0eaa\u0ec8\u0e96\u0ebb\u0e87\u0ea2\u0eb2\u0e87.<\/li>\n<li>\u0e81\u0eb2\u0e99\u0e8d\u0eb1\u0e94\u0e82\u0eb5\u0ec9\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e8d\u0e97\u0eb5\u0ec8\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0ec3\u0eaa\u0ec8\u0e96\u0ebb\u0e87\u0ea2\u0eb2\u0e87\u0e9b\u0eb9\u0e81\u0ec0\u0eab\u0eb1\u0e94: \u0ec0\u0ead\u0ebb\u0eb2\u0e82\u0eb5\u0ec9\u0ec0\u0ea5\u0eb7\u0ec8\u0ead\u0e8d\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e9a\u0eb1\u0e99\u0e88\u0eb8\u0ec3\u0eaa\u0ec8 \u0e96\u0ebb\u0e87\u0ea2\u0eb2\u0e87\u0e95\u0ecd\u0eb2\u0ec3\u0eab\u0ec9\u0ec1\u0edc\u0ec9\u0e99\u0e9e\u0ecd\u0e9b\u0eb0\u0ea1\u0eb2\u0e99, \u0eab\u0eb8\u0e9a\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0ec0\u0e82\u0ebb\u0ec9\u0eb2, \u0ec3\u0eaa\u0ec8\u0e9b\u0ead\u0e81\u0e84\u0ecd\u0ec0\u0ead\u0ebb\u0eb2\u0ea2\u0eb2\u0e87\u0e9a\u0ea7\u0ec9\u0e87\u0eae\u0eb1\u0e94 \u00a0\u0ec1\u0ea5\u0eb0 \u0ead\u0eb1\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0e94\u0ea7\u0ec9\u0e8d\u0eaa\u0ecd\u0eb2\u0ea5\u0eb5 \u0e81\u0eb2\u0e99\u0e8d\u0eb1\u0e94\u0ea1\u0eb5 2 \u0ea7\u0eb4\u0e97\u0eb5\u0e84\u0eb7: \u0ec3\u0e8a\u0ec9\u0e94\u0ec9\u0ea7\u0e8d\u0ea1\u0eb7 \u0ec1\u0ea5\u0eb0 \u0ec3\u0e8a\u0ec9\u0e94\u0ec9\u0ea7\u0e8d\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ead\u0eb1\u0e94\u0e96\u0ebb\u0e87.<\/li>\n<li>\u0e81\u0eb2\u0e99\u0edc\u0eb6\u0ec9\u0e87\u0e96\u0ebb\u0e87\u0ec0\u0eab\u0eb1\u0e94: \u0ec0\u0ead\u0ebb\u0eb2\u0e96\u0ebb\u0e87\u0e81\u0ec9\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94\u0ec4\u0e9b\u0edc\u0eb6\u0ec9\u0e87\u0ec3\u0eaa\u0ec8\u0e96\u0eb1\u0e87 (\u0e9f\u0eb8\u0ec9\u0e8d) \u0ec3\u0e99\u0e96\u0eb1\u0e87\u0edc\u0eb6\u0ec9\u0e87 \u0ec3\u0eaa\u0ec8\u0e95\u0eb0\u0ec1\u0e81\u0e87\u0eaa\u0eb9\u0e87 15 \u00a0\u0e8a\u0eb1\u0e87\u0e95\u0eb4\u0ec1\u0ea1\u0eb1\u0e94,\u0ec3\u0eaa\u0ec8 \u0e99\u0ecd\u0ec9\u0eb2 12 \u0e8a\u0eb1\u0e87\u0e95\u0eb4\u0ec1\u0ea1\u0eb1\u0e94, \u0ec0\u0ead\u0ebb\u0eb2\u0e96\u0ebb\u0e87\u0ec0\u0eab\u0eb1\u0e94\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ec4\u0e9b\u0ea5\u0ebd\u0e99\u0ec3\u0e99\u0e96\u0eb1\u0e87\u0ec0\u0eae\u0eb1\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0e8a\u0eb1\u0ec9\u0e99\u0e82\u0eb7\u0ec9\u0e99\u0ea1\u0eb2\u0e88\u0ebb\u0e99\u0ec0\u0e95\u0eb1\u0ea1, \u0ec0\u0ead\u0ebb\u0eb2\u0ec1\u0e9e\u0ea2\u0eb2\u0e87\u0e9b\u0eb4\u0e94, \u0ec0\u0e8a\u0eb7\u0ead\u0e81\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0ec1\u0edc\u0ec9\u0e99, \u0e81\u0eb2\u0e99\u0edc\u0eb7\u0ec9\u0e87\u0ec3\u0e8a\u0ec0\u0ea7\u0ea5\u0eb2 3 \u0e8a\u0ebb\u0ec8\u0ea7\u0ec2\u0ea1\u0e87.<\/li>\n<li>\u0ea7\u0eb5\u0e97\u0eb5\u0ec0\u0e82\u0ec8\u0e8d\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec0\u0eab\u0eb1\u0e94: \u0e81\u0eb2\u0e99\u0ec0\u0e82\u0ec8\u0e8d\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec0\u0eab\u0eb1\u0e94\u0e95\u0ec9\u0ead\u0e87\u0e81\u0ebd\u0ea1\u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99\u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e95\u0eb0\u0e81\u0ebd\u0e87\u0ec0\u0eab\u0ebc\u0ebb\u0ec9\u0eb2 90, \u0ec0\u0eab\u0ebc\u0ebb\u0ec9\u0eb2 90, \u0ea2\u0eb2\u0e87\u0e9a\u0ea7\u0ec9\u0e87, \u0ec0\u0e88\u0ec9\u0e8d\u0e9b\u0eb4\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0e81\u0ec9\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94\u0ec0\u0ea7\u0ea5\u0eb2\u0ec0\u0e82\u0ec8\u0e8d\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0e95\u0ec9\u0ead\u0e87\u0ea5\u0ec9\u0eb2\u0e87\u0ea1\u0eb7\u0ec3\u0eab\u0ec9\u0eaa\u0eb0\u0ead\u0eb2\u0e94, \u0e81\u0ec8\u0ead\u0e99\u0e88\u0eb0\u0ec0\u0e82\u0ec8\u0e8d\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec0\u0eab\u0eb1\u0e94 \u0ec0\u0ead\u0ebb\u0eb2\u0ec1\u0e81\u0ec9\u0ea7\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec0\u0eab\u0eb1\u0e94\u0ea1\u0eb2\u0e95\u0eb5\u0ec3\u0eab\u0ec9\u0eab\u0ebb\u0ea7\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec1\u0e95\u0e81\u0ead\u0ead\u0e81 \u0e88\u0eb2\u0e81\u0e99\u0eb1\u0ec9\u0e99\u0ec0\u0ead\u0ebb\u0eb2\u0ec4\u0e9f\u0ea5\u0ebb\u0e99\u0e9b\u0eb2\u0e81\u0e81\u0ea7\u0e94\u0ec1\u0e81\u0ec9\u0ea7 \u0ec1\u0ea5\u0ec9\u0ea7 \u0e94\u0eb6\u0e87\u0ec0\u0ead\u0ebb\u0eb2\u0eaa\u0eb3\u0ea5\u0eb5\u0ead\u0eb1\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0ec0\u0eab\u0eb1\u0e94\u0ead\u0ead\u0e81 \u0ec0\u0e82\u0ec8\u0e8d\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ea5\u0ebb\u0e87\u0ec3\u0eaa\u0ec8\u0e96\u0ebb\u0e87\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 20-30 \u0ec0\u0ea1\u0eb1\u0e94. \u0ec1\u0ea5\u0ec9\u0ea7\u0eaa\u0eb1\u0ec8\u0e99\u0ec6\u0ec3\u0eab\u0ec9\u0ec0\u0ea1\u0eb1\u0e94\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e81\u0eb0\u0e88\u0eb2\u0e8d\u0ead\u0ead\u0e81\u0e82\u0eb2\u0ec9\u0e87\u0e96\u0ebb\u0e87\u0e94\u0eb2\u0ec9\u0e99\u0ec3\u0e99, \u0ec0\u0ead\u0ebb\u0eb2\u0eaa\u0ecd\u0eb2\u0ea5\u0eb5\u0ead\u0eb1\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0ec4\u0ea7\u0ec9\u0e84\u0eb7\u0ec0\u0e81\u0ebb\u0ec8\u0eb2\u0ec1\u0ea5\u0ec9\u0ea7 \u0ec0\u0ead\u0ebb\u0eb2\u0ec0\u0e88\u0ec9\u0e8d\u0ead\u0eb1\u0e94 \u0ec0\u0ead\u0ebb\u0eb2\u0ea2\u0eb2\u0e87\u0e9a\u0ec9\u0ea7\u0e87\u0ea1\u0eb1\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0ec4\u0ea7\u0ec9.<\/li>\n<li>\u0e81\u0eb2\u0e99\u0e9a\u0ebb\u0ec8\u0ea1\u0e96\u0ebb\u0e87\u0e81\u0ec9\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94: \u0ec0\u0ead\u0ebb\u0eb2\u0e96\u0ebb\u0e87\u0e81\u0ec9\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94\u0e97\u0eb5\u0ec8\u0ec0\u0e82\u0ec8\u0e8d\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec0\u0eab\u0eb1\u0e94\u0ec3\u0eaa\u0ec8\u0ec1\u0ea5\u0ec9\u0ea7\u0ec4\u0e9b\u0e9a\u0ebb\u0ec8\u0ea1\u0ec4\u0ea7\u0ec9\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0e9a\u0ebb\u0ec8\u0ea1,\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0e9a\u0ebb\u0ec8\u0ea1\u0e84\u0ea7\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0eb0\u0ead\u0eb2\u0e94, \u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e96\u0ec8\u0eb2\u0e8d\u0ec0\u0e97\u0eaa\u0eb0\u0e94\u0ea7\u0e81, \u0e81\u0eb2\u0e99\u0e9a\u0ebb\u0ec8\u0ea1\u0ec3\u0e8a\u0ec9\u0ec0\u0ea7\u0ea5\u0eb2 25-30 \u0ea7\u0eb1\u0e99. \u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec0\u0eab\u0eb1\u0e94\u0e81\u0ecd\u0e88\u0eb0\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0e95\u0ebb\u0ea7 \u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb5\u0e82\u0eb2\u0ea7\u0ec0\u0e95\u0eb1\u0ea1\u0e96\u0ebb\u0e87.<\/li>\n<li>\u0e81\u0eb2\u0e99\u0ec0\u0e9b\u0eb4\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0e81\u0ec9\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94: \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec0\u0eab\u0eb1\u0e94\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0e95\u0ebb\u0ea7\u0ec0\u0e95\u0eb1\u0ea1\u0e96\u0ebb\u0e87\u0e81\u0ec9\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94\u0ec1\u0ea5\u0ec9\u0ea7, \u0ec0\u0ead\u0ebb\u0eb2\u0e96\u0ebb\u0e87\u0e81\u0ec9\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ec4\u0e9b\u0ea5\u0ebd\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e96\u0ea7 \u0ec0\u0e9b\u0eb1\u0e99\u0e8a\u0eb1\u0ec9\u0e99\u0e82\u0eb7\u0ec9\u0e99\u0ec1\u0ea5\u0ec9\u0ea7\u0e81\u0ecd\u0ec8\u0ec0\u0e9b\u0eb5\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0ec2\u0e94\u0e8d\u0ec3\u0e8a\u0ec9\u0ea1\u0eb5\u0e94\u0e9b\u0eb2\u0e94\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0ec3\u0eab\u0ec9\u0e81\u0ea7\u0ec9\u0eb2\u0e87\u0ec0\u0e96\u0eb4\u0e87\u0e9a\u0ec8\u0eb2\u0e82\u0ead\u0e87\u0e96\u0ebb\u0e87\u0ec0\u0eab\u0eb1\u0e94 , \u0e94\u0eb6\u0e87\u0ec0\u0ead\u0ebb\u0eb2\u0e96\u0ebb\u0e87\u0ea2\u0eb2\u0e87\u0e97\u0eb5\u0ec8\u0e9b\u0eb2\u0e94\u0ead\u0ead\u0e81\u0ead\u0eb0\u0e99\u0eb2\u0ec4\u0ea1\u0e9b\u0eb2\u0e81\u0e96\u0ebb\u0e87\u0ec3\u0eab\u0ec9\u0eaa\u0eb0\u0ead\u0eb2\u0e94\u0e88\u0ebb\u0e99\u0edd\u0ebb\u0e94\u0e97\u0eb8\u0e81\u0ec6\u0e96\u0ebb\u0e87\u0eab\u0ea5\u0eb1\u0e87\u0e88\u0eb2\u0e81\u0e99\u0eb1\u0ec9\u0e99\u0e81\u0ecd\u0eab\u0ebb\u0e94\u0e99\u0ecd\u0ec9\u0eb2.<\/li>\n<\/ol>\n<p class=\"question\">2. \u0e81\u0eb2\u0e99\u0e9a\u0ebb\u0ea7\u0ea5\u0eb0\u0e9a\u0eb1\u0e94\u0eae\u0eb1\u0e81\u0eaa\u0eb2<\/p>\n<p>\u0ec3\u0eab\u0ec9\u0edd\u0eb1\u0ec8\u0e99\u0ead\u0eb0\u0e99\u0eb2\u0ec4\u0ea1\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0eaa\u0eb0\u0ead\u0eb2\u0e94, \u0eab\u0ebb\u0e94\u0e99\u0ecd\u0ec9\u0eb2\u0ec3\u0eab\u0ec9\u0e84\u0ea7\u0eb2\u0ea1\u0e8a\u0ec8\u0eb8\u0ea1\u0eaa\u0eb0\u0edd\u0ec8\u0ecd\u0eb2\u0eaa\u0eb0\u0ec0\u0edd\u0eb5 \u0e95\u0eb4\u0e94\u0e95\u0eb2\u0ea1\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ec1\u0ea1\u0e87\u0ec4\u0ea1\u0ec9\u0eaa\u0eb1\u0e94\u0e95\u0eb9\u0e9e\u0eb7\u0e94\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0ea1\u0eb2\u0ea5\u0ebb\u0e9a\u0e81\u0ea7\u0e99.<\/p>\n<p class=\"question\">3. \u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0ea1\u0eb1\u0e81\u0ec0\u0e81\u0eb5\u0e94\u0e81\u0eb1\u0e9a\u0ec0\u0eab\u0eb1\u0e94\u0e82\u0ead\u0e99\u0e82\u0eb2\u0ea7<\/p>\n<p>\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ea5\u0eb2\u0e82\u0ebd\u0ea7, \u0ea5\u0eb2\u0ec4\u0e82\u0ec8\u0e9b\u0eb2,\u0e96\u0ebb\u0e87\u0ec0\u0eab\u0eb1\u0e94\u0ec0\u0e99\u0ebb\u0ec8\u0eb2 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0edc\u0ead\u0e99\u0ec0\u0e88\u0eb2\u0eb0\u0ec0\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0e96\u0ebb\u0e87\u0ec0\u0eab\u0eb1\u0e94\u0ec0\u0eaa\u0e8d \u0ec0\u0eab\u0eb1\u0e94\u0e9a\u0ecd\u0ec8\u0ead\u0ead\u0e81\u0e94\u0ead\u0e81, \u0e81\u0eb2\u0e99\u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99 \u0e95\u0ec9\u0ead\u0e87\u0ead\u0eb0\u0e99\u0eb2\u0ec4\u0ea1\u0ec0\u0eae\u0eb7\u0ead\u0e99\u0ec0\u0eab\u0eb1\u0e94, \u0ead\u0eb0\u0e99\u0eb2\u0ec4\u0ea1\u0e96\u0ebb\u0e87\u0ec0\u0eab\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0eaa\u0eb0\u0ead\u0eb2\u0e94.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Source \u0ec1\u0e9a\u0e9a\u0eae\u0ebd\u0e99\u0ea7\u0eb4\u0e8a\u0eb2\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9d\u0eb1\u0e87<\/p>\n","protected":false},"template":"","format":"standard","story-type":[122,116,118],"class_list":["post-12078","story","type-story","status-publish","format-standard","hentry","story-type-enterprise","story-type-farming","story-type-sustainability"],"acf":{"pkl_story_headline":"\u0ec0\u0eab\u0eb1\u0e94\u0e82\u0ead\u0e99\u0e82\u0eb2\u0ea7\u0ec0\u0eab\u0eb1\u0e94\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0e97\u0eb5\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e9b\u0eb9\u0e81\u0ec3\u0eaa\u0ec8\u0ec0\u0e9a\u0ebb\u0ec9\u0eb2\u0e9b\u0eb9\u0e81 \u0ec1\u0ea5\u0eb0 \u0ec3\u0eaa\u0ec8\u0e82\u0ead\u0e99\u0ec4\u0ea1\u0ec9\u0ec4\u0e94\u0ec9\u0eab\u0ebc\u0eb2\u0e8d\u0e8a\u0eb0\u0e99\u0eb4\u0e94 (\u0ec4\u0ea1\u0ec9\u0ea1\u0ec8\u0ea7\u0e87, \u0ec4\u0ea1\u0ec9\u0e95\u0eb5\u0ec9\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ead\u0eb7\u0ec8\u0e99\u0ec6) \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec0\u0e81\u0eb1\u0e9a\u0e81\u0eb9\u0ec9\u0e88\u0eb2\u0e81\u0e97\u0eb3\u0ea1\u0eb0\u0e8a\u0eb2\u0e94 \u0ec2\u0e94\u0e8d\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0ec1\u0ea1\u0ec8\u0e99\u0e9b\u0ec8\u0eb2\u0ec2\u0e84\u0e81\u0e88\u0eb2\u0e81\u0ec4\u0ea1\u0ec9\u0e95\u0eb2\u0e8d.","pkl_story_authors":"Andy Souvanphakdy","pkl_story_image":4978,"pkl_story_video":"","pkl_story_image_credits":"phakhaolao.la","pkl_story_file":null,"pkl_story_story_types":[]},"_links":{"self":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story\/12078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/types\/story"}],"wp:attachment":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/media?parent=12078"}],"wp:term":[{"taxonomy":"story-type","embeddable":true,"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story-type?post=12078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}