{"id":12139,"date":"2020-12-10T00:00:00","date_gmt":"2020-12-09T17:00:00","guid":{"rendered":"https:\/\/phakhaolao.la\/story\/%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%ba%9e%e0%ba%b7%e0%ba%94%e0%ba%9b%e0%ba%b0%e0%ba%aa%e0%ba%bb%e0%ba%a1%e0%ba%9b%e0%ba%b0%e0%ba%aa%e0%ba%b2%e0%ba%99-%e0%bb%81%e0%ba%a5%e0%ba%b0\/"},"modified":"2025-03-19T13:06:47","modified_gmt":"2025-03-19T06:06:47","slug":"%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%ba%9e%e0%ba%b7%e0%ba%94%e0%ba%9b%e0%ba%b0%e0%ba%aa%e0%ba%bb%e0%ba%a1%e0%ba%9b%e0%ba%b0%e0%ba%aa%e0%ba%b2%e0%ba%99-%e0%bb%81%e0%ba%a5%e0%ba%b0","status":"publish","type":"story","link":"https:\/\/phakhaolao.la\/en\/story\/%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%ba%9e%e0%ba%b7%e0%ba%94%e0%ba%9b%e0%ba%b0%e0%ba%aa%e0%ba%bb%e0%ba%a1%e0%ba%9b%e0%ba%b0%e0%ba%aa%e0%ba%b2%e0%ba%99-%e0%bb%81%e0%ba%a5%e0%ba%b0\/","title":{"rendered":"\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e9b\u0eb0\u0eaa\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0e9e\u0eb7\u0e94\u0edd\u0eb9\u0e99\u0ea7\u0ebd\u0e99"},"content":{"rendered":"<p><strong>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e9b\u0eb0\u0eaa\u0eb2\u0e99<\/strong> <\/p>\n<p>\u0ec1\u0ea1\u0ec8\u0e99\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0e9e\u0eb7\u0e94\u0e97\u0eb5\u0ec8\u0e95\u0ec8\u0eb2\u0e87\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0ea1\u0eb2\u0e9b\u0eb9\u0e81\u0ec3\u0e81\u0ec9\u0e81\u0eb1\u0e99 \u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec0\u0e9b\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0e99\u0ecd\u0eb2\u0ec3\u0e8a\u0ec9\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0e94\u0eb4\u0e99\u0ec3\u0eab\u0ec9\u0ec0\u0e81\u0eb5\u0e94\u0e9b\u0eb0\u0ec2\u0eab\u0e8d\u0e94\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9b\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0ec2\u0e84\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e82\u0ead\u0e87\u0e94\u0eb4\u0e99 \u0ec1\u0ea5\u0eb0 \u0e95\u0ebb\u0ec9\u0e99\u0e9e\u0eb7\u0e94, \u0e81\u0eb2\u0e99\u0e99\u0ecd\u0eb2\u0ec0\u0ead\u0ebb\u0eb2\u0e9e\u0eb7\u0e94\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0ead\u0eb2\u0eab\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99\u0ea1\u0eb2\u0e9b\u0eb9\u0e81\u0ea5\u0ea7\u0ea1\u0e81\u0eb1\u0e99 \u0e88\u0eb0\u0e8a\u0ec8\u0ea7\u0e8d\u0eab\u0ebc\u0eb8\u0e94\u0e9c\u0ec8\u0ead\u0e99\u0e81\u0eb2\u0e99\u0e8d\u0eb2\u0e94\u0ec1\u0e8d\u0ec8\u0e87\u0ead\u0eb2\u0eab\u0eb2\u0e99\u0e81\u0eb1\u0e99\u0ea5\u0eb0\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0e9e\u0eb7\u0e94. \u0e94\u0ec9\u0eb2\u0e99\u0ea5\u0eb8\u0ec8\u0ea1\u0e99\u0eb5\u0ec9\u0e84\u0eb7\u0e9a\u0eb2\u0e87\u0e82\u0ecd\u0ec9\u0ec1\u0e99\u0eb0\u0e99\u0ecd\u0eb2 \u0eab\u0ebc\u0eb7 \u0ec1\u0e99\u0ea7\u0e84\u0eb4\u0e94\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0e9e\u0eb7\u0e94\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99\u0ea1\u0eb2\u0e9b\u0eb9\u0e81\u0ec3\u0e81\u0ec9\u0e84\u0ebd\u0e87\u0e81\u0eb1\u0e99. <\/p>\n<p>\u00a0<\/p>\n<ol>\n<li>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e95\u0ebb\u0ec9\u0e99\u0eaa\u0eb9\u0e87\u0ec3\u0e81\u0ec9\u0e81\u0eb1\u0e9a\u0e9e\u0eb7\u0e94\u0e95\u0ebb\u0ec9\u0e99\u0ec0\u0e95\u0ec9\u0e8d\u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e9b\u0eb9\u0e81\u0eaa\u0eb2\u0ea5\u0eb5\u0e9b\u0ebb\u0e99\u0e81\u0eb1\u0e9a\u0e81\u0eb0\u0ea5\u0ecd\u0eb2\u0e9b\u0eb5, \u0e9b\u0eb9\u0e81\u0e9c\u0eb1\u0e81\u0e81\u0eb2\u0e94\u0e99\u0eb2\u00a0\u0eab\u0ea5\u0eb7 \u0e9a\u0eca\u0ead\u0e81\u0e84\u0ecc\u0ea5\u0eb5\u00a0\u0e9b\u0ebb\u0e99\u0e81\u0eb1\u0e9a\u0e9c\u0eb1\u0e81\u0eab\u0ebb\u0ea1, \u0e9c\u0eb1\u0e81\u0eaa\u0eb0\u0eab\u0ebc\u0eb1\u0e94 \u0ec1\u0ea5\u0eb0 \u0e9b\u0eb9\u0e81\u0e95\u0ebb\u0ec9\u0e99\u0ec4\u0ea1\u0ec9\u0e81\u0eb4\u0e99\u0eab\u0ea1\u0eb2\u0e81\u0ec3\u0e81\u0ec9\u0e81\u0eb1\u0e9a\u0e9e\u0eb7\u0e94\u0e9c\u0eb1\u0e81. <\/li>\n<li>\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0eae\u0eb2\u0e81\u0e8d\u0eb2\u0ea7\u0ec3\u0e81\u0ec9\u0e81\u0eb1\u0e9a\u0e9e\u0eb7\u0e94\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0eae\u0eb2\u0e81\u0eaa\u0eb1\u0ec9\u0e99\u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e95\u0ebb\u0ec9\u0e99\u0e9c\u0eb1\u0e81\u0ead\u0eb5\u0ec8\u0eae\u0eb8\u0ea1 \u0eab\u0ebc\u0eb7 \u0e95\u0ebb\u0ec9\u0e99\u0ec1\u0e84\u0e81\u0eb1\u0e9a\u0e9c\u0eb1\u0e81\u0e81\u0eb0\u0ec0\u0e9e\u0ebb\u0eb2, \u0e9c\u0eb1\u0e81\u0ead\u0eb5\u0ec8\u0e95\u0eb9\u0ec8. <\/li>\n<li>\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0ec0\u0e84\u0eb7\u0ead\u0ec3\u0e81\u0ec9\u0e81\u0eb1\u0e9a\u0e9e\u0eb7\u0e94\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0ea2\u0eb1\u0ec8\u0e87\u0e9c\u0ebb\u0e99\u0ea5\u0ebb\u0e87\u0e94\u0eb4\u0e99\u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e9b\u0eb9\u0e81\u0e96\u0ebb\u0ec8\u0ea7\u0e8d\u0eb2\u0ea7 \u0eab\u0ebc\u0eb7 \u0eaa\u0eb2\u0ea5\u0eb5\u0ec3\u0e81\u0ec9\u0e81\u0eb1\u0e9a\u0e9c\u0eb1\u0e81\u0eaa\u0eb0\u0eab\u0ebc\u0eb1\u0e94, \u0e9c\u0eb1\u0e81\u0e9a\u0ebb\u0ea7.<\/li>\n<li>\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0ec3\u0e9a\u0e81\u0ec9\u0ea7\u0eb2\u0e87\u0ec3\u0e81\u0ec9\u0e81\u0eb1\u0e9a\u0e9e\u0eb7\u0e94\u0ec3\u0e9a\u0ec1\u0e84\u0e9a\u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e9b\u0eb9\u0e81\u0e81\u0eb0\u0eab\u0ebc\u0ecd\u0ec8\u0eb2\u0e9b\u0eb5\u0ec3\u0e81\u0ec9\u0e81\u0eb1\u0e9a\u0e81\u0eb0\u0ea5\u0ebb\u0e94 (\u0ec1\u0e84\u0ea3\u0ead\u0e94).<\/li>\n<li>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e9b\u0eb0\u0eaa\u0eb2\u0e99\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0ec3\u0e8a\u0ec9\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0ea2\u0ec8\u0eb2\u0e87\u0ec0\u0e95\u0eb1\u0ea1\u0e97\u0eb5\u0ec8 \u0e9e\u0ec9\u0ead\u0ea1\u0e97\u0eb1\u0e87\u0e8a\u0ec8\u0ea7\u0e8d\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec2\u0e84\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0eab\u0e99\u0ec9\u0eb2\u0e94\u0eb4\u0e99 \u0ec1\u0ea5\u0eb0 \u0e9e\u0eb7\u0e94\u0e9c\u0eb1\u0e81.<\/li>\n<\/ol>\n<p><strong>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0eab\u0ea1\u0eb9\u0e99\u0ea7\u0ebd\u0e99 <\/strong><\/p>\n<p>\u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87\u0e81\u0eb2\u0e99\u0e99\u0eb3\u0e9e\u0eb7\u0e94\u0e95\u0ec8\u0eb2\u0e87\u0e8a\u0eb0\u0e99\u0eb4\u0e94 \u0eab\u0ebc\u0eb7 \u0e95\u0eb0\u0e81\u0eb8\u0e99\u0ea1\u0eb2\u0e9b\u0eb9\u0e81\u0ec0\u0e9b\u0eb1\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0ec0\u0ea7\u0ea5\u0eb2\u0e95\u0ecd\u0ec8\u0ec0\u0e99\u0eb7\u0ec8\u0ead\u0e87\u0ec3\u0e99\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99 \u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ecd\u0eb2\u0e84\u0eb1\u0e99\u0e95\u0ecd\u0ec8\u0e82\u0ebb\u0e87\u0ec0\u0e82\u0e94\u0e81\u0eb2\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94 \u0ec1\u0ea5\u0eb0 \u0e87\u0ec8\u0eb2\u0e8d\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0e95\u0eb4\u0e9a\u0eb1\u0e94, \u0e97\u0eb5\u0ec8\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0e9e\u0eb7\u0e94\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0e88\u0eb0\u0e94\u0eb9\u0e94\u0e8a\u0eb6\u0ea1\u0ec0\u0ead\u0ebb\u0eb2\u0e97\u0eb2\u0e94\u0ead\u0eb2\u0eab\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99, \u0e97\u0eb1\u0e87\u0e94\u0eb6\u0e87\u0e94\u0eb9\u0e94\u0ec0\u0ead\u0ebb\u0eb2\u0eaa\u0eb1\u0e94\u0e95\u0eb9\u0e9e\u0eb7\u0e94 \u0ec1\u0ea5\u0eb0 \u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99 \u00a0\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0eab\u0ea1\u0eb9\u0e99\u0ea7\u0ebd\u0e99\u0e9e\u0eb7\u0e94\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0ead\u0eb7\u0ec8\u0e99\u0ea1\u0eb2\u0e9b\u0eb9\u0e81\u0ec3\u0eaa\u0ec8\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0e81\u0eb2\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec3\u0e99\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0e94\u0eb9\u0e81\u0eb2\u0e99 \u0e88\u0eb6\u0ec8\u0e87\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0e95\u0eb4\u0e94\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0e8a\u0ecd\u0ec9\u0eb2\u0e84\u0eb7\u0e99\u0e88\u0eb2\u0e81\u0eaa\u0eb1\u0e94\u0e95\u0eb9\u0e9e\u0eb7\u0e94, \u0e9e\u0eb0\u0e8d\u0eb2\u0e94\u0ec1\u0e9a\u0e9a\u0ec0\u0e81\u0ebb\u0ec8\u0eb2 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec0\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0e9e\u0eb7\u0e94\u0ec1\u0e82\u0e87\u0ec1\u0eae\u0e87. <\/p>\n<p>\u0e9e\u0eb0\u0e8d\u0eb2\u0e8d\u0eb2\u0ea1\u0eab\u0ebc\u0eb5\u0e81\u0ec0\u0ea7\u0eb1\u0ec9\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e95\u0eb0\u0e81\u0eb8\u0e99\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99\u0ec3\u0eaa\u0ec8\u0e9a\u0ec8\u0ead\u0e99\u0ec0\u0e81\u0ebb\u0ec8\u0eb2\u0ead\u0eb5\u0e81\u0e84\u0eb1\u0ec9\u0e87 \u0ec1\u0ea5\u0eb0 \u0e9a\u0ecd\u0ec8\u0e84\u0ea7\u0e99\u0e9b\u0eb0\u0ec3\u0eab\u0ec9\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0ec0\u0e9b\u0ebb\u0ec8\u0eb2 \u0ec0\u0e9e\u0eb2\u0eb0\u0ea7\u0ec8\u0eb2\u0eaa\u0eb0\u0e9e\u0eb2\u0e9a \u0e82\u0ead\u0e87\u0e94\u0eb4\u0e99\u0e88\u0eb0\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0ea5\u0ebb\u0e87\u0e96\u0ec9\u0eb2\u0ea1\u0eb1\u0e99\u0e96\u0eb7\u0e81\u0ec1\u0eaa\u0e87\u0ec1\u0e94\u0e94 \u0ec1\u0ea5\u0eb0 \u0e95\u0eb2\u0e81\u0e9d\u0ebb\u0e99\u0eab\u0ebc\u0eb2\u0e8d\u0ec0\u0e81\u0eb5\u0e99\u0ec4\u0e9b. \u0e94\u0eb1\u0ec8\u0e87\u0e99\u0eb1\u0ec9\u0e99, \u0e84\u0ea7\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0eb1\u0e99\u0e8a\u0ebb\u0ec8\u0ea7\u0e84\u0eb2\u0ea7\u0ec3\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0e99\u0eb5\u0ec9 \u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e96\u0ebb\u0ec8\u0ea7, \u0ea1\u0eb1\u0e99\u0e94\u0ec9\u0eb2\u0e87 \u0eab\u0ebc\u0eb7 \u0e9e\u0eb7\u0e94\u0eaa\u0eb0\u0eab\u0ea1\u0eb8\u0e99\u0ec4\u0e9e\u0e95\u0ec8\u0eb2\u0e87\u0ec6. \u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0e88\u0eb0\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e9a\u0eb1\u0e99\u0eab\u0eb2\u0ec3\u0e99\u0ec0\u0ea7\u0ea5\u0eb2\u0ea1\u0eb5\u0eab\u0e8d\u0ec9\u0eb2\u0ec3\u0e99\u0eaa\u0ea7\u0e99\u00a0\u0ec3\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0e97\u0eb3\u0ead\u0eb4\u0e94\u0e82\u0ead\u0e87\u0e81\u0eb2\u0e99\u0ea5\u0eb4\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0ea5\u0eb0\u0e94\u0eb9\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec3\u0eab\u0ea1\u0ec8, \u0e81\u0ecd\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e99\u0ecd\u0eb2\u0ec3\u0e8a\u0ec9\u0ec0\u0eaa\u0e94\u0e9e\u0eb7\u0e94\u0eaa\u0eb5\u0e82\u0ebd\u0ea7\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0ec4\u0e9b\u0ec0\u0eae\u0eb1\u0e94\u0e9d\u0eb8\u0ec8\u0e99\u0e9a\u0ebb\u0ec8\u0ea1 \u0ec1\u0ea5\u0eb0 \u0e99\u0ecd\u0ec9\u0eb2\u0e8a\u0eb5\u0ea7\u0eb0\u0e9e\u0eb2\u0e9a. \u0eab\u0ebc\u0eb1\u0e87\u0e88\u0eb2\u0e81\u0e97\u0eb5\u0ec8\u0ead\u0eb0\u0e99\u0eb2\u0ec4\u0ea1\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8 \u0ec1\u0ea5\u0eb0 \u0e95\u0eb7\u0ec8\u0ea1\u0e9d\u0eb8\u0ec8\u0e99\u0e9a\u0ebb\u0ec8\u0ea1\u0e97\u0eb5\u0ec8\u0ec0\u0eab\u0ebc\u0eb7\u0ead\u0e88\u0eb2\u0e81\u0ea5\u0eb0\u0e94\u0eb9\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e97\u0eb5\u0ec8\u0e9c\u0ec8\u0eb2\u0e99\u0ea1\u0eb2\u0ec3\u0eaa\u0ec8\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0ea5\u0ec9\u0ea7, \u0e84\u0ea7\u0e99\u0ec4\u0e96\u0e9e\u0ea7\u0e99\u0e94\u0eb4\u0e99\u0ec0\u0ea5\u0eb4\u0e81\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 20-30 \u0e8a\u0eb1\u0e87\u0e95\u0eb5\u0ec1\u0ea1\u0eb1\u0e94 \u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec3\u0eab\u0ec9\u0e9d\u0eb8\u0ec8\u0e99\u0e9a\u0ebb\u0ec8\u0ea1\u0e97\u0eb5\u0ec8\u0ec0\u0e95\u0eb5\u0ea1\u0ec3\u0eaa\u0ec8\u0ec3\u0eab\u0ea1\u0ec8\u0ec4\u0e94\u0ec9\u0e9b\u0ebb\u0e99\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e81\u0eb1\u0e9a\u0e94\u0eb4\u0e99.<\/p>\n<p><strong>\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e88\u0eb2\u0e81: <\/strong>\u0eaa\u0ea7\u0e99\u0e9e\u0eb6\u0e81\u0eaa\u0eb2\u0e8a\u0eb2\u0e94\u0e9c\u0eb2\u0e95\u0eb1\u0e94\u0ec1\u0e81\u0ec9(\u0eab\u0ebc\u0ea7\u0e87\u0e9e\u0eb0\u0e9a\u0eb2\u0e87)<\/p>\n","protected":false},"template":"","format":"standard","story-type":[116,118],"class_list":["post-12139","story","type-story","status-publish","format-standard","hentry","story-type-farming","story-type-sustainability"],"acf":{"pkl_story_headline":"\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e9e\u0eb7\u0e94\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e9b\u0eb0\u0eaa\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0e9e\u0eb7\u0e94\u0edc\u0eb9\u0e99\u0ea7\u0ebd\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0eab\u0e8d\u0eb1\u0e87?","pkl_story_authors":"Sakhone INTHAVONG","pkl_story_image":5202,"pkl_story_video":"","pkl_story_image_credits":"phakhaolao.la","pkl_story_file":null,"pkl_story_story_types":[]},"_links":{"self":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story\/12139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/types\/story"}],"wp:attachment":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/media?parent=12139"}],"wp:term":[{"taxonomy":"story-type","embeddable":true,"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story-type?post=12139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}