{"id":12246,"date":"2019-08-19T00:00:00","date_gmt":"2019-08-19T00:00:00","guid":{"rendered":"https:\/\/phakhaolao.la\/story\/%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%9d%e0%ba%b2%e0%ba%81%e0%ba%87%e0%ba%b2\/"},"modified":"2024-10-22T22:34:21","modified_gmt":"2024-10-22T22:34:21","slug":"%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%9d%e0%ba%b2%e0%ba%81%e0%ba%87%e0%ba%b2","status":"publish","type":"story","link":"https:\/\/phakhaolao.la\/en\/story\/%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%9d%e0%ba%b2%e0%ba%81%e0%ba%87%e0%ba%b2\/","title":{"rendered":"\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0edd\u0eb2\u0e81\u0e87\u0eb2"},"content":{"rendered":"<p><strong>\u0e81\u0eb2\u0e99\u0e81\u0eb0\u0e81\u0ebd\u0ea1\u0e94\u0eb4\u0e99:\u00a0<\/strong><br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0ec0\u0e9b\u0eb1\u0e99\u0e94\u0eb4\u0e99\u0e9c\u0eb8\u0e9c\u0eb8\u0e8d\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0eb2\u0e8d\u0e99\u0ec9\u0ecd\u0eb2\u0e94\u0eb5 \u0ec1\u0ea5\u0eb0 \u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ead\u0eb8\u0e94\u0ebb\u0ea1\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u0e97\u0eb2\u0e87\u0e94\u0ec9\u0eb2\u0e99\u0ead\u0eb2\u0eab\u0eb2\u0e99\u0e9e\u0ecd\u0eaa\u0ebb\u0ea1\u0e84\u0ea7\u0e99\u00a0<br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0e94\u0ead\u0e99 \u0eab\u0ebc\u0eb7 \u0eaa\u0eb9\u0e87 \u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ea5\u0eb0\u0e9a\u0eb2\u0e8d\u0e99\u0ec9\u0ecd\u0eb2\u0ec4\u0e94\u0ec9.\u00a0<br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0e82\u0eb8\u0e94 \u0eab\u0ebc\u0eb7 \u0ec4\u0e96\u0e9e\u0ea7\u0e99\u0e94\u0eb4\u0e99 (\u0e96\u0ec9\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0e94\u0eb4\u0e99\u0e9c\u0eb8\u0e9c\u0eb8\u0ec8\u0e8d\u0e88\u0eb0\u0ec4\u0e96 1-2 \u0e84\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8\u0e96\u0ec9\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0e94\u0eb4\u0e99\u0edc\u0ebd\u0ea7\u0e95\u0ec9\u0ead\u0e87\u0ec4\u0e96 2-3 \u0e84\u0eb1\u0ec9\u0e87).<br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0ec0\u0eae\u0eb1\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0edc\u0eb2\u0e99\u0ec3\u0eab\u0e8d\u0ec8\u0e82\u0eb0\u0edc\u0eb2\u0e94 3-5 \u0ec1\u0ea1\u0eb1\u0e94 \u0ec1\u0ea5\u0eb0 \u0ec3\u0eab\u0ec9\u0ea1\u0eb5\u0eae\u0ead\u0e87\u0ea5\u0eb0\u0eab\u0ea7\u0ec8\u0eb2\u0e87\u0edc\u0eb2\u0e99\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0eaa\u0eb0\u0e94\u0ea7\u0e81\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e94\u0eb9\u0ec1\u0ea5\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec0\u0e81\u0eb5\u0e94\u0e9e\u0eb0\u0e8d\u0eb2\u0e94 \u0eab\u0ebc\u0eb7 \u0ec1\u0ea1\u0e87\u0ec4\u0ea1\u0ec9\u0ea5\u0eb0\u0e9a\u0eb2\u0e94.\u00a0<br \/><strong>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81:\u00a0<\/strong><br \/><strong>\u0ea7\u0eb4\u0e97\u0eb5\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ea1\u0eb5 2 \u0ea7\u0eb4\u0e97\u0eb5\u0e84\u0eb7 <\/strong>: \u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0e9a\u0e9a\u0eab\u0ea7\u0ec8\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0e9a\u0e9a\u0ec2\u0eae\u0e8d\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e96\u0ea7\u00a0<br \/>\n\u00a0 &#8211;\u00a0\u00a0<strong>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0e9a\u0e9a\u0eab\u0ea7\u0ec8\u0eb2\u0e99:<\/strong> \u0eab\u0ea7\u0ec8\u0eb2\u0e99\u0ec1\u0e81\u0ec8\u0e99\u0ec3\u0eab\u0ec9\u0e81\u0eb0\u0ec1\u0e88\u0e81\u0e81\u0eb0\u0e88\u0eb2\u0e8d \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb0\u0edd\u0ecd\u0ec8\u0eb2\u0eaa\u0eb0\u0ec0\u0edd\u0eb5\u0ec1\u0ea5\u0ec9\u0ea7\u0e84\u0eb2\u0e94\u0e94\u0eb4\u0e99\u0e9b\u0ebb\u0e81\u0ec0\u0e97\u0eb4\u0e87\u0edc\u0ec9\u0eb2\u0e94\u0eb4\u0e99, \u0eab\u0ea7\u0ec8\u0eb2\u0e99 \u0ec1\u0e81\u0ec8\u0e99\u0e87\u0eb2\u0e9b\u0eb0\u0ea5\u0eb4\u0ea1\u0eb2\u0e99 1-2 \u0e81\u0eb4\u0ec2\u0ea5\/\u0ec4\u0ea5.\u00a0<br \/>\n\u00a0 &#8211;\u00a0\u00a0<strong>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0e9a\u0e9a\u0ec2\u0eae\u0e8d\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e96\u0ea7<\/strong>: \u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0e9a\u0e9a\u0ec2\u0eae\u0e8d\u0ec0\u0ea1\u0eb1\u0e94\u0ec1\u0ea1\u0ec8\u0e99\u0e88\u0eb0\u0ea1\u0eb5\u0ec4\u0ea5\u0e8d\u0eb0\u0eab\u0ec8\u0eb2\u0e87\u0e82\u0ead\u0e87\u0ec1\u0e96\u0ea7\u0e9b\u0eb9\u0e81 50&#215;10 \u0e8a\u0ea1.\u00a0<br \/><strong>\u0ea7\u0eb4\u0e97\u0eb5\u0e9a\u0ebb\u0ea7\u0ea5\u0eb0\u0e9a\u0eb1\u0e94\u0eae\u0eb1\u0e81\u0eaa\u0eb2:\u00a0<\/strong><br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0e87\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb7\u0e94\u0e97\u0eb5\u0ec8\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0e94\u0eb9\u0ec1\u0ea5\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0edc\u0ec9\u0ead\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0e9e\u0eb7\u0e94\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0ead\u0eb7\u0ec8\u0e99\u0e9e\u0ebd\u0e87\u0ec1\u0e95\u0ec8\u0e81\u0ebd\u0ea1\u0e94\u0eb4\u0e99\u0ec3\u0eab\u0ec9\u0e96\u0eb7\u0e81\u0ea7\u0eb4\u0e97\u0eb5 \u0ec1\u0ea5\u0eb0 \u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0ecd\u0ec8\u0e87\u0ead\u0e81\u0e87\u0eb2\u0ea1\u0eaa\u0eb0\u0edd\u0ecd\u0ec8\u0eb2\u0eaa\u0eb0\u0ec0\u0edd\u0eb5.\u00a0<br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0ea7\u0eb4\u0e97\u0eb5\u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0eaa\u0eb1\u0e94: \u0ec3\u0eab\u0ec9\u0e99\u0ecd\u0eb2\u0ec0\u0ead\u0ebb\u0eb2\u0ec3\u0e9a\u0eaa\u0eb5\u0ec3\u0e84\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87, \u0eab\u0e8d\u0ec9\u0eb2\u0edc\u0ead\u0e99\u0e99\u0ec8\u0eb2\u0e8d , \u0ec0\u0e84\u0eb7\u0ead\u0ec0\u0e82\u0ebb\u0eb2\u0eae\u0ecd&#8230; \u0ea1\u0eb2\u0e9f\u0eb1\u0e81\u0ec3\u0eab\u0ec9\u0ea1\u0eb8\u0ec8\u0e99\u0ec1\u0ea5\u0ec9\u0ea7\u0ec0\u0ead\u0ebb\u0eb2\u0ec1\u0e8a\u0ec8\u0ec3\u0eaa\u0ec8\u0e99\u0ec9\u0ecd\u0eb2\u0e9b\u0eb0\u0ec4\u0ea7\u0ec9\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 15-30 \u0ea1\u0eb7\u0ec9 \u0e81\u0ecd\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e99\u0ecd\u0eb2\u0ec0\u0ead\u0ebb\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0e94\u0eb1\u0ec8\u0e87\u0e81\u0ec8\u0eb2\u0ea7\u0ea1\u0eb2\u0eaa\u0eb5\u0e94\u0ec3\u0eaa\u0ec8\u0e95\u0ebb\u0ec9\u0e99\u0e87\u0eb2\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0eaa\u0eb1\u0e94\u0e95\u0eb9\u0e9e\u0eb7\u0e94\u0ec4\u0e94\u0ec9.<br \/><strong>\u0e81\u0eb2\u0e99\u0ec0\u0e81\u0eb1\u0e9a\u0e81\u0ec8\u0ebd\u0ea7:<\/strong><br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0ec3\u0eab\u0ec9\u0eaa\u0eb1\u0e87\u0ec0\u0e81\u0e94\u0ec4\u0ea5\u0e8d\u0eb0\u0eaa\u0eb8\u0e81\u0e82\u0ead\u0e87\u0edd\u0eb2\u0e81\u0e87\u0eb2, \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0e87\u0eb2\u0ec0\u0e96\u0eb4\u0e87\u0ead\u0eb2\u0e8d\u0eb8\u0ec0\u0e81\u0eb1\u0e9a\u0e81\u0ec8\u0ebd\u0ea7\u0ec3\u0e9a\u0e88\u0eb0\u0ea1\u0eb5\u0eaa\u0eb5\u0ec0\u0eab\u0ebc\u0eb7\u0ead\u0e87 \u0ec1\u0ea5\u0eb0 \u0ea5\u0ebb\u0ec8\u0e99\u0ec0\u0e81\u0eb7\u0ead\u0e9a\u0edd\u0ebb\u0e94, \u0e9d\u0eb1\u0e81\u0e82\u0ead\u0e87\u0edd\u0eb2\u0e81\u0e87\u0eb2\u0e88\u0eb0\u0e9b\u0ec8\u0ebd\u0e99\u0eaa\u0eb5\u0e88\u0eb2\u0e81\u0eaa\u0eb5\u0e82\u0ebd\u0ea7\u0ea1\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb5\u0ec0\u0eab\u0ebc\u0eb7\u0ead\u0e87, \u0ec0\u0ea1\u0eb1\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb5\u0e99\u0ec9\u0ecd\u0eb2\u0e95\u0eb2\u0e99 (\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e87\u0eb2\u0e94\u0ecd\u0eb2\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0eb0\u0e9d\u0eb1\u0e81\u0e97\u0eb5 3 \u0e88\u0eb2\u0e81\u0e8d\u0ead\u0e94\u0ead\u0ead\u0e81\u0ea1\u0eb2\u0ec0\u0e9a\u0eb4\u0ec8\u0e87\u0e96\u0ec9\u0eb2\u0ec0\u0ea1\u0eb1\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb5\u0e99\u0ec9\u0ecd\u0eb2\u0e95\u0eb2\u0e99\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0ea7\u0ec8\u0eb2\u0ec1\u0e81\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec0\u0e81\u0eb1\u0e9a\u0e81\u0ec8\u0ebd\u0ea7\u0ec4\u0e94\u0ec9.\u00a0<br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0ec3\u0eab\u0ec9\u0ec0\u0ead\u0ebb\u0eb2\u0ea1\u0eb5\u0e94\u0e95\u0eb1\u0e94\u0e81\u0ec9\u0ead\u0e87\u0e9d\u0eb1\u0e81 \u0eab\u0ebc\u0eb7 \u0eab\u0ebc\u0ebb\u0e81\u0ec0\u0ead\u0ebb\u0eb2\u0e97\u0eb1\u0e87\u0e95\u0ebb\u0ec9\u0e99\u0e81\u0ecd\u0ec4\u0e94\u0ec9\u0ec1\u0e95\u0ec8\u0e9e\u0eb0\u0e8d\u0eb2\u0e8d\u0eb2\u0ea1\u0e9a\u0ecd\u0ec8\u0ec3\u0eab\u0ec9\u0e94\u0eb4\u0e99\u0e95\u0eb4\u0e94\u0ec0\u0ea1\u0eb1\u0e94\u0e87\u0eb2.\u00a0<br \/><strong>\u0e81\u0eb2\u0e99\u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0ec4\u0ea7\u0ec9\u0e81\u0eb4\u0e99\u0e8d\u0eb2\u0ea7\u0e99\u0eb2\u0e99:<\/strong><br \/>\n\u00a0 \u00a0 \u0e95\u0eb2\u0e81\u0ec3\u0eab\u0ec9\u0ec1\u0eab\u0ec9\u0e87\u0ec1\u0ea5\u0ec9\u0ea7\u0ec0\u0e81\u0eb1\u0e9a\u0ec4\u0ea7\u0ec9\u0e81\u0eb4\u0e99\u0e8d\u0eb2\u0ea7\u0e99\u0eb2\u0e99, \u0eaa\u0eb0\u0e81\u0eb1\u0e94\u0ec0\u0eae\u0eb1\u0e94\u0e99\u0ec9\u0ecd\u0eb2\u0ea1\u0eb1\u0e99\u0e87\u0eb2, \u0ec0\u0eae\u0eb1\u0e94\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0eab\u0ea1\u0ebb\u0ea1 &#8230;\u00a0<br \/><strong>\u0e84\u0eb8\u0e99\u0e9b\u0eb0\u0ec2\u0eab\u0e8d\u0e94:<\/strong><br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0ea1\u0eb5\u0e84\u0eb8\u0e99\u0e84\u0ec8\u0eb2\u0e97\u0eb2\u0e87\u0e94\u0ec9\u0eb2\u0e99\u0eaa\u0eb2\u0e99\u0ead\u0eb2\u0eab\u0eb2\u0e99\u0eaa\u0eb9\u0e87\u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0ec3\u0eab\u0ec9\u0ec2\u0e9b\u0ea3\u0e95\u0eb5\u0e99, \u0ec4\u0e82\u0ea1\u0eb1\u0e99 &#8230;\u00a0<br \/>\n\u00a0 &#8211;\u00a0\u00a0\u0e9b\u0eb9\u0e81\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e81\u0eb4\u0e99 \u0ec1\u0ea5\u0eb0 \u0e82\u0eb2\u0e8d\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0e9e\u0eb2\u0e8d\u0ec3\u0e99\u0e9a\u0ec9\u0eb2\u0e99, \u0e97\u0ec9\u0ead\u0e87\u0e96\u0eb4\u0ec8\u0e99, \u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94 \u0ec1\u0ea5\u0eb0 \u0e95\u0ec8\u0eb2\u0e87\u0e9b\u0eb0\u0ec0\u0e97\u0e94.<\/p>\n<p>\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e88\u0eb2\u0e81: \u0e9b\u0eb7\u0ec9\u0ea1\u0ec0\u0e99\u0eb7\u0ec9\u0ead\u0ec3\u0e99\u0e84\u0eb9\u0ec8\u0ea1\u0eb7\u0ec0\u0e9d\u0eb4\u0e81\u0ead\u0ebb\u0e9a\u0eae\u0ebb\u0ea1\u0e81\u0eb2\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e81\u0eb0\u0eaa\u0eb4\u0e81\u0ecd\u0eb2\u0e82\u0ead\u0e87\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0eaa\u0eb6\u0e81\u0eaa\u0eb2<\/p>\n","protected":false},"template":"","format":"standard","story-type":[122,116,118],"class_list":["post-12246","story","type-story","status-publish","format-standard","hentry","story-type-enterprise","story-type-farming","story-type-sustainability"],"acf":{"pkl_story_headline":"\u0ec0\u0e97\u0eb1\u0e81\u0e99\u0eb4\u0e81\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0edd\u0eb2\u0e81\u0e87\u0eb2\u0ec3\u0eab\u0ec9\u0ec4\u0e94\u0ec9\u0e84\u0eb8\u0e99\u0e99\u0eb0\u0e9e\u0eb2\u0e9a\u0e94\u0eb5\u0ec2\u0e94\u0e8d\u0e9a\u0ecd\u0ec8\u0ec3\u0e8a\u0ec9\u0eaa\u0eb2\u0e99\u0ec0\u0e84\u0ea1\u0eb5","pkl_story_authors":"Soulivanh BOUNTHAMMY","pkl_story_image":5838,"pkl_story_video":"","pkl_story_image_credits":"www.trekearth.com","pkl_story_file":null,"pkl_story_story_types":[]},"_links":{"self":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story\/12246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/types\/story"}],"wp:attachment":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/media?parent=12246"}],"wp:term":[{"taxonomy":"story-type","embeddable":true,"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story-type?post=12246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}