{"id":12250,"date":"2019-08-13T00:00:00","date_gmt":"2019-08-13T00:00:00","guid":{"rendered":"https:\/\/phakhaolao.la\/story\/%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%9d%e0%ba%b2%e0%ba%81%e0%ba%99%e0%ba%b1%e0%ba%94\/"},"modified":"2024-11-25T12:56:20","modified_gmt":"2024-11-25T12:56:20","slug":"%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%9d%e0%ba%b2%e0%ba%81%e0%ba%99%e0%ba%b1%e0%ba%94","status":"publish","type":"story","link":"https:\/\/phakhaolao.la\/en\/story\/%e0%ba%81%e0%ba%b2%e0%ba%99%e0%ba%9b%e0%ba%b9%e0%ba%81%e0%bb%9d%e0%ba%b2%e0%ba%81%e0%ba%99%e0%ba%b1%e0%ba%94\/","title":{"rendered":"\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94"},"content":{"rendered":"<p><strong>\u0e81\u0eb2\u0e99\u0e81\u0eb0\u0e81\u0ebd\u0ea1\u0e94\u0eb4\u0e99:\u00a0<\/strong>\u0ec4\u0e96\u0e94\u0eb4\u0e99\u0e9b\u0eb0\u0ec4\u0ea7\u0ec9 7-10 \u0ea1\u0eb7\u0ec9\u0eab\u0ebc\u0eb1\u0e87\u0e88\u0eb2\u0e81\u0e99\u0eb1\u0ec9\u0e99, \u0ec3\u0eab\u0ec9\u0e9e\u0ea7\u0e99\u0e94\u0eb4\u0e99\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e81\u0eb1\u0e9a\u0e9d\u0eb8\u0ec8\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec0\u0eae\u0eb1\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0edc\u0eb2\u0e99\u0eaa\u0eb9\u0e87\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 15 \u0e8a\u0ea1 \u0eab\u0ebc\u0eb7 \u0e82\u0eb8\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0e82\u0eb8\u0ea1\u0ec0\u0e9b\u0eb1\u0e99\u0ec1\u0e96\u0ea7, \u0ec4\u0ea5\u0e8d\u0eb0\u0eab\u0ec8\u0eb2\u0e87\u0e82\u0ead\u0e87\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0e95\u0ebb\u0ec9\u0e99\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 30&#215;50 \u0e8a\u0ea1.\u00a0<br \/><strong>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e9a\u0ebb\u0ea7\u0ea5\u0eb0\u0e9a\u0eb1\u0e94\u0eae\u0eb1\u0e81\u0eaa\u0eb2<\/strong><br \/><strong>\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ea1\u0eb5 2 \u0ea7\u0eb4\u0e97\u0eb5\u0e84\u0eb7 :<\/strong> \u0ec3\u0e8a\u0ec9\u0edc\u0ecd\u0ec8\u0ea5\u0eb9\u0e81 (\u0ea5\u0eb0\u0e94\u0eb9\u0e9d\u0ebb\u0e99) \u0ec1\u0ea5\u0eb0 \u0ec3\u0e8a\u0ec9\u0e88\u0eb8\u0e81\u0eab\u0ebb\u0ea7\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0e9b\u0eb9\u0e81 (\u0ea5\u0eb0\u0e94\u0eb9\u0ec1\u0ea5\u0ec9\u0e87).\u00a0<br \/>\n\u00a0 &#8211;\u00a0\u00a0<strong>\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0edc\u0ecd\u0ec8\u0e9b\u0eb9\u0e81:<\/strong> \u0ec1\u0ea1\u0ec8\u0e99\u0e95\u0ec9\u0ead\u0e87\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0ec0\u0ead\u0ebb\u0eb2\u0edc\u0ecd\u0ec8\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e81\u0eb1\u0e99\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec3\u0eab\u0ec9\u0ead\u0ead\u0e81\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec3\u0e99\u0ec4\u0ea5\u0e8d\u0eb0\u0e94\u0ebd\u0ea7\u0e81\u0eb1\u0e99, \u0ec4\u0ea5\u0e8d\u0eb0\u0e81\u0eb2\u0e99\u0ead\u0ead\u0e81\u0e94\u0ead\u0e81-\u0edd\u0eb2\u0e81\u0ec1\u0ea1\u0ec8\u0e99\u0ec3\u0e8a\u0ec9\u0ec0\u0ea7\u0ea5\u0eb2 8-12 \u0ec0\u0e94\u0eb7\u0ead\u0e99.<br \/>\n\u00a0 &#8211;\u00a0\u00a0<strong>\u0eaa\u0ecd\u0eb2\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e88\u0eb8\u0e81\u0eab\u0ebb\u0ea7\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0e9b\u0eb9\u0e81:<\/strong> \u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0ea1\u0ec8\u0e99\u0ec3\u0e8a\u0ec9\u0ec0\u0ea7\u0ea5\u0eb2 10-14 \u0ec0\u0e94\u0eb7\u0ead\u0e99, \u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0ec1\u0ea1\u0ec8\u0e99\u0ec3\u0e8a\u0ec9\u0eaa\u0ebd\u0ea1\u0e82\u0eb8\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0e82\u0eb8\u0ea1 \u0ec1\u0ea5\u0eb0 \u0e99\u0ecd\u0eb2\u0edc\u0ecd\u0ec8 \u0eab\u0ebc\u0eb7 \u0e88\u0eb8\u0e81\u0ea5\u0ebb\u0e87\u0e9d\u0eb1\u0ec8\u0e87\u0ec1\u0ea5\u0ec9\u0ea7\u0ec3\u0e8a\u0ec9\u0e94\u0eb4\u0e99\u0e96\u0ebb\u0ea1\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 10-15 \u0e8a\u0ea1.<br \/><strong>\u0e81\u0eb2\u0e99\u0eab\u0ebb\u0e94\u0e99\u0ec9\u0ecd\u0eb2:\u00a0<\/strong>\u0ec1\u0ea1\u0ec8\u0e99\u0ead\u0eb5\u0e87\u0e95\u0eb2\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1\u0e82\u0ead\u0e87\u0eaa\u0eb0\u0e9e\u0eb2\u0e9a\u0ead\u0eb2\u0e81\u0eb2\u0e94. \u0e96\u0ec9\u0eb2\u0eab\u0eb2\u0e81\u0ea1\u0eb5\u0e9b\u0eb0\u0ea5\u0eb4\u0ea1\u0eb2\u0e99\u0e99\u0ec9\u0ecd\u0eb2\u0e9d\u0ebb\u0e99\u0eaa\u0eb0\u0edd\u0ecd\u0ec8\u0eb2\u0eaa\u0eb0\u0ec0\u0edd\u0eb5 \u0eab\u0ebc\u0eb7 \u0e95\u0ebb\u0e81\u0e95\u0eb2\u0ea1\u0ea5\u0eb0\u0e94\u0eb9\u0e81\u0eb2\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e9a\u0ecd\u0ec8\u0e88\u0ecd\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ec9\u0ead\u0e87\u0ec3\u0eab\u0ec9\u0e99\u0ecd\u0ec9\u0eb2. \u0eab\u0ea1\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb6\u0e94\u0e97\u0eb5\u0ec8\u0e97\u0ebb\u0e99\u0e97\u0eb2\u0e99\u0e95\u0ecd\u0ec8\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0eab\u0ec9\u0e87\u0ec1\u0ea5\u0ec9\u0e87.<br \/><strong>\u0e81\u0eb2\u0e99\u0ec3\u0eaa\u0ec8\u0e9d\u0eb8\u0ec8\u0e99:\u00a0<\/strong>\u0ec0\u0e99\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb2\u0e81\u0ea7\u0ec8\u0eb2\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0e9e\u0eb7\u0e94\u0e97\u0eb5\u0ec8\u0e97\u0ebb\u0e99\u0ec1\u0ea5\u0ec9\u0e87 \u0ec1\u0ea5\u0eb0 \u0e84\u0ec8\u0ead\u0e99\u0e82\u0ec9\u0eb2\u0e87\u0ec0\u0e81\u0eb5\u0e94\u0ec4\u0e94\u0ec9\u0e87\u0ec8\u0eb2\u0e8d\u0e95\u0eb2\u0ea1\u0e97\u0ecd\u0eb2\u0ea1\u0eb0\u0e8a\u0eb2\u0e94, \u0e94\u0eb1\u0ec8\u0e87\u0e99\u0eb1\u0ec9\u0e99, \u0e81\u0eb2\u0e99\u0ec3\u0eaa\u0ec8\u0e9d\u0eb8\u0ec8\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0ec3\u0eab\u0ec9\u0ead\u0eb5\u0e87\u0e95\u0eb2\u0ea1\u0eaa\u0eb0\u0e9e\u0eb2\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0ead\u0eb8\u0e94\u0ebb\u0ea1\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u0e82\u0ead\u0e87\u0e94\u0eb4\u0e99, \u0e96\u0ec9\u0eb2\u0eab\u0eb2\u0e81\u0e94\u0eb4\u0e99\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0ead\u0eb8\u0e94\u0ebb\u0ea1\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u0edc\u0ec9\u0ead\u0e8d\u0ec0\u0eae\u0ebb\u0eb2\u0e81\u0ecd\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0eaa\u0ec8\u0e9d\u0eb8\u0ec8\u0e99\u0e84\u0ead\u0e81 \u0eab\u0ebc\u0eb7 \u0e9d\u0eb8\u0ec8\u0ea1\u0e9a\u0ebb\u0ec8\u0ea1 \u0e95\u0ebb\u0ec9\u0e99\u0edc\u0eb6\u0ec8\u0e87\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 1-2 \u0e81\u0ebc\u0eb2\u0ea1\/\u0e82\u0eb8\u0ea1 \u0eab\u0ebc\u0eb1\u0e87\u0e88\u0eb2\u0e81\u0e9b\u0eb9\u0e81\u0ec4\u0e94\u0ec9 3 \u0ec0\u0e94\u0eb7\u0ead\u0e99.\u00a0<br \/><strong>\u0e81\u0eb2\u0e99\u0ec0\u0e81\u0eb1\u0e9a\u0e81\u0ec8\u0ebd\u0ea7:<\/strong>\u00a0\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0eaa\u0eb1\u0e87\u0ec0\u0e81\u0e94\u0ec0\u0eab\u0eb1\u0e99\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0eaa\u0eb8\u0e81\u0ea1\u0eb5\u0eaa\u0eb5\u0ec0\u0eab\u0ebc\u0eb7\u0ead\u0e87\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 80% \u0ec1\u0ea1\u0ec8\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec0\u0e81\u0eb1\u0e9a\u0e81\u0ec8\u0ebd\u0ea7\u0ec4\u0e94\u0ec9. \u0e9b\u0eb0\u0ec3\u0eab\u0ec9\u0ea5\u0eb9\u0e81\u0e84\u0eb2\u0e95\u0ebb\u0ec9\u0e99\u0e8d\u0eb4\u0ec8\u0e87\u0ec0\u0e9b\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0e94\u0eb5\u0ea5\u0ebb\u0e94\u0e8a\u0eb2\u0e94\u0e88\u0eb0\u0eab\u0ea7\u0eb2\u0e99\u0e94\u0eb5.<br \/><strong>\u0e84\u0eb8\u0e99\u0e84\u0ec8\u0eb2\u0e97\u0eb2\u0e87\u0ec2\u0e9e\u0e8a\u0eb0\u0e99\u0eb2\u0e81\u0eb2\u0e99:\u00a0<\/strong>\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0ec1\u0ea1\u0ec8\u0e99\u0edd\u0eb2\u0e81\u0ec4\u0ea1\u0ec9\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0edc\u0eb6\u0ec8\u0e87\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0ea7\u0eb4\u0e95\u0eb2\u0ea1\u0eb4\u0e99\u0e8a\u0eb5 (C) \u0eaa\u0eb9\u0e87 (47.8 \u0ea1\u0eb5\u0e99\u0ea5\u0eb5\u0e81\u0ebc\u0eb2\u0ea1 (mg)\u0ec3\u0e99 100 \u0e81\u0ebc\u0eb2\u0ea1 (g)). \u0e99\u0ead\u0e81\u0e88\u0eb2\u0e81\u0e99\u0eb1\u0ec9\u0e99\u0e8d\u0eb1\u0e87\u0ea1\u0eb5\u0ea7\u0eb4\u0e95\u0eb2\u0ea1\u0eb4\u0e99\u0ec0\u0ead (A), \u0e9a\u0eb5 (B), \u0ec1\u0ea5\u0eb0 \u0ead\u0eb5 (E); \u0e97\u0eb2\u0e94\u0ec4\u0e82\u0ea1\u0eb1\u0e99, \u0ec2\u0e9b\u0ea3\u0e95\u0eb5\u0e99, \u0ec4\u0e8d\u0ead\u0eb2\u0eab\u0eb2\u0e99, \u0e99\u0ec9\u0ecd\u0eb2\u0e95\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0e97\u0eb2\u0e94\u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0ead\u0eb5\u0e81\u0e94\u0ec9\u0ea7\u0e8d.<br \/><strong>\u0e81\u0eb2\u0e99\u0ec1\u0e9b\u0eae\u0eb9\u0e9a\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0ec4\u0ea7\u0ec9\u0e81\u0eb4\u0e99\u0e8d\u0eb2\u0ea7\u0e99\u0eb2\u0e99 (\u0e81\u0ea7\u0e99\u0eab\u0ea1\u0eb2\u0e81\u0e99\u0eb1\u0e94):\u00a0<\/strong>\u0e99\u0ecd\u0eb2\u0ec0\u0ead\u0ebb\u0eb2\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0ea1\u0eb2\u0e9b\u0ead\u0e81, \u0e9b\u0eb2\u0e94\u0ec0\u0ead\u0ebb\u0eb2\u0e95\u0eb2\u0ead\u0ead\u0e81 \u0ec1\u0ea5\u0ec9\u0ea7\u0e9b\u0eb2\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ead\u0e99\u0e99\u0ec9\u0ead\u0e8d\u0ec6 \u0eab\u0ebc\u0eb7 \u0e9d\u0eb1\u0e81, \u0e8a\u0ead\u0e8d\u0e84\u0eb7\u0e95\u0ecd\u0eb2\u0edd\u0eb2\u0e81\u0eab\u0eb8\u0ec8\u0e87 \u0eab\u0ebc\u0eb7 \u0eab\u0eb1\u0ec9\u0e99\u0ec1\u0ea5\u0ec9\u0ea7\u0e99\u0ecd\u0eb2\u0ec4\u0e9b \u0e95\u0ebb\u0ec9\u0ea1\u0ec2\u0e94\u0e8d\u0e9a\u0ecd\u0ec8\u0ec4\u0e94\u0ec9\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e99\u0ec9\u0ecd\u0eb2\u0ec1\u0ea5\u0ec9\u0ea7\u0e99\u0ecd\u0eb2\u0ec0\u0ead\u0ebb\u0eb2\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0ea5\u0ebb\u0e87\u0edd\u0ecd\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0e99\u0ecd\u0ec9\u0eb2\u0e95\u0eb2\u0e99\u0e8a\u0eb2\u0e8d\u0e82\u0eb2\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e81\u0eb7\u0ead\u0ec3\u0e99\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94 1 \u0e81\u0eb4\u0ec2\u0ea5, \u0e99\u0ec9\u0ecd\u0eb2\u0e95\u0eb2\u0e99\u0e8a\u0eb2\u0e8d\u0e82\u0eb2\u0ea7 300 \u0e81\u0ebc\u0eb2\u0ea1 (\u0e82\u0eb6\u0ec9\u0e99\u0e81\u0eb1\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ebb\u0ec9\u0ea1 \u0ec1\u0ea5\u0eb0 \u0eab\u0ea7\u0eb2\u0e99\u0e82\u0ead\u0e87\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94) \u0ec1\u0ea5\u0eb0 \u0ec0\u0e81\u0eb7\u0ead 1 \u0e9a\u0ec8\u0ea7\u0e87\u0e81\u0eb2\u0ec0\u0e9f, \u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e95\u0ebb\u0ec9\u0ea1\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0e95\u0ec9\u0ead\u0e87\u0ec4\u0e94\u0ec9\u0ec0\u0ead\u0ebb\u0eb2\u0ec3\u0e88\u0ec3\u0eaa\u0ec8\u0e84\u0ebb\u0e99\u0ea2\u0eb9\u0ec8\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94 \u0ec1\u0ea5\u0eb0 \u0ec3\u0e8a\u0ec9\u0ec4\u0e9f\u0ea5\u0eb0\u0e94\u0eb1\u0e9a\u0ead\u0ec8\u0ead\u0e99\u0e96\u0ec9\u0eb2\u0ec4\u0e9f\u0ec1\u0eae\u0e87\u0e88\u0eb0\u0ec4\u0edd\u0ec9\u0e9e\u0eb7\u0ec9\u0e99\u0edd\u0ecd\u0ec9.\u00a0<br \/>\n\u0e81\u0eb2\u0e99\u0e95\u0ebb\u0ec9\u0ea1\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0ec3\u0e8a\u0ec9\u0ec0\u0ea7\u0ea5\u0eb2\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 60-90 \u0e99\u0eb2\u0e97\u0eb5 (\u0ead\u0eb5\u0e87\u0e95\u0eb2\u0ea1\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0e97\u0eb5\u0ec8\u0e9b\u0eb2\u0e94) \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0eaa\u0eb1\u0e87\u0ec0\u0e81\u0e94\u0ec0\u0eab\u0eb1\u0e99\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0e97\u0eb5\u0ec8\u0ec0\u0eae\u0ebb\u0eb2\u0e95\u0ebb\u0ec9\u0ea1 \u0eab\u0ebc\u0eb7\u0ead\u0e9b\u0eb0\u0ea1\u0eb2\u0e99\u0ec0\u0e84\u0eb4\u0ec8\u0e87\u0edc\u0eb6\u0ec8\u0e87\u0e88\u0eb2\u0e81\u0e9b\u0eb0\u0ea5\u0eb4\u0ea1\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0ec0\u0eae\u0ebb\u0eb2\u0e95\u0ebb\u0ec9\u0ea1, \u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0e82\u0eb8\u0ec9\u0e99\u0eab\u0e99\u0ebd\u0ea7 \u0ec1\u0ea5\u0eb0 \u0e9b\u0ec8\u0ebd\u0e99\u0eaa\u0eb5\u0ec1\u0ea5\u0ec9\u0ea7 (\u0e88\u0eb2\u0e81\u0eaa\u0eb5\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb5\u0e84\u0ec9\u0eb2\u0e8d\u0e99\u0ecd\u0ec9\u0eb2\u0e95\u0eb2\u0e99\u0ec4\u0edd\u0ec9) \u0ec1\u0ea1\u0ec8\u0e99\u0e96\u0eb7\u0ea7\u0ec8\u0eb2\u0eaa\u0ecd\u0eb2\u0ec0\u0ea5\u0eb1\u0e94.<br \/>\n\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0e81\u0ea7\u0e99\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94\u0e97\u0ec8\u0eb2\u0e99\u0e8d\u0eb1\u0e87\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e99\u0ecd\u0eb2\u0ec0\u0ead\u0ebb\u0eb2\u0e81\u0eb0\u0e97\u0eb4\u0edd\u0eb2\u0e81\u0e9e\u0ec9\u0eb2\u0ea7\u0ea1\u0eb2\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0ec8\u0ea7\u0e99\u0e9b\u0eb0\u0eaa\u0ebb\u0ea1\u0ec4\u0e94\u0ec9\u0ead\u0eb5\u0e81\u0ec2\u0e94\u0e8d\u0ead\u0eb5\u0e87\u0e95\u0eb2\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ea1\u0eb1\u0e81\u0e82\u0ead\u0e87\u0ec1\u0e95\u0ec8\u0ea5\u0eb0\u0e84\u0ebb\u0e99.<\/p>\n<p>\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e88\u0eb2\u0e81: \u0e9b\u0eb7\u0ec9\u0ea1\u0ec0\u0e99\u0eb7\u0ec9\u0ead\u0ec3\u0e99\u0e84\u0eb9\u0ec8\u0ea1\u0eb7\u0ec0\u0e9d\u0eb4\u0e81\u0ead\u0ebb\u0e9a\u0eae\u0ebb\u0ea1\u0e81\u0eb2\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e81\u0eb0\u0eaa\u0eb4\u0e81\u0ecd\u0eb2\u0e82\u0ead\u0e87\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0eaa\u0eb6\u0e81\u0eaa\u0eb2<\/p>\n","protected":false},"template":"","format":"standard","story-type":[122,116,118],"class_list":["post-12250","story","type-story","status-publish","format-standard","hentry","story-type-enterprise","story-type-farming","story-type-sustainability"],"acf":{"pkl_story_headline":"\u0ec0\u0e95\u0eb1\u0e81\u0e99\u0eb4\u0e81\u0e81\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0edd\u0eb2\u0e81\u0e99\u0eb1\u0e94 \u0ec4\u0ea7\u0ec9\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0eae\u0eb1\u0e9a\u0e9b\u0eb0\u0e97\u0eb2\u0e99\u0ec0\u0ead\u0e87\u0e9e\u0eb2\u0e8d\u0ec3\u0e99\u0e84\u0ead\u0e9a\u0e84\u0ebb\u0ea7, \u0e96\u0ec9\u0eb2\u0ec0\u0eab\u0ebc\u0eb7\u0ead\u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ecd\u0ec8\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e99\u0eb3\u0ea1\u0eb2\u0e82\u0eb2\u0e8d\u0ec4\u0e94\u0ec9.","pkl_story_authors":"Soulivanh BOUNTHAMMY","pkl_story_image":5877,"pkl_story_video":"","pkl_story_image_credits":"sokhaviek.com","pkl_story_file":null,"pkl_story_story_types":[]},"_links":{"self":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story\/12250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/types\/story"}],"wp:attachment":[{"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/media?parent=12250"}],"wp:term":[{"taxonomy":"story-type","embeddable":true,"href":"https:\/\/phakhaolao.la\/en\/wp-json\/wp\/v2\/story-type?post=12250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}